
{"id":1472,"date":"2017-10-10T19:46:12","date_gmt":"2017-10-10T18:46:12","guid":{"rendered":"https:\/\/assemblee-nationale.bj\/?page_id=1472"},"modified":"2017-10-10T19:46:12","modified_gmt":"2017-10-10T18:46:12","slug":"services","status":"publish","type":"page","link":"https:\/\/assemblee-nationale.bj\/index.php\/services\/","title":{"rendered":"Services"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-1472","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/assemblee-nationale.bj\/index.php\/wp-json\/wp\/v2\/pages\/1472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/assemblee-nationale.bj\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/assemblee-nationale.bj\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/assemblee-nationale.bj\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/assemblee-nationale.bj\/index.php\/wp-json\/wp\/v2\/comments?post=1472"}],"version-history":[{"count":1,"href":"https:\/\/assemblee-nationale.bj\/index.php\/wp-json\/wp\/v2\/pages\/1472\/revisions"}],"predecessor-version":[{"id":1474,"href":"https:\/\/assemblee-nationale.bj\/index.php\/wp-json\/wp\/v2\/pages\/1472\/revisions\/1474"}],"wp:attachment":[{"href":"https:\/\/assemblee-nationale.bj\/index.php\/wp-json\/wp\/v2\/media?parent=1472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/assemblee-nationale.bj\/index.php\/wp-json\/wp\/v2\/categories?post=1472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/assemblee-nationale.bj\/index.php\/wp-json\/wp\/v2\/tags?post=1472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}